{"id":1327,"date":"2021-02-06T10:32:49","date_gmt":"2021-02-06T10:32:49","guid":{"rendered":"https:\/\/wir-lernen-weiter.ch\/?p=1327"},"modified":"2022-03-30T13:43:15","modified_gmt":"2022-03-30T12:43:15","slug":"anderen-helfen-2-4-working-poor","status":"publish","type":"post","link":"https:\/\/wir-lernen-weiter.ch\/it\/anderen-helfen-2-4-working-poor\/","title":{"rendered":"Aiutare gli altri (2\/4): Poveri lavoratori"},"content":{"rendered":"<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/wir-lernen-weiter.ch\/wp-content\/uploads\/2021\/02\/2021-02-06-11_11_06-Praesentation1-PowerPoint-1024x682.png\" alt=\"\" class=\"wp-image-1329\" srcset=\"https:\/\/wir-lernen-weiter.ch\/wp-content\/uploads\/2021\/02\/2021-02-06-11_11_06-Praesentation1-PowerPoint-1024x682.png 1024w, https:\/\/wir-lernen-weiter.ch\/wp-content\/uploads\/2021\/02\/2021-02-06-11_11_06-Praesentation1-PowerPoint-300x200.png 300w, https:\/\/wir-lernen-weiter.ch\/wp-content\/uploads\/2021\/02\/2021-02-06-11_11_06-Praesentation1-PowerPoint-768x511.png 768w, https:\/\/wir-lernen-weiter.ch\/wp-content\/uploads\/2021\/02\/2021-02-06-11_11_06-Praesentation1-PowerPoint.png 1170w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Il team di osservatori SOS<\/figcaption><\/figure>\n\n\n\n<p><strong>Con la seconda edizione del nostro blog sulle partnership, vi presentiamo la Fondazione SOS Observer. Per noi \u00e8 il centro di verifica per tutte le persone che sono colpite dalla povert\u00e0 ma che non ricevono ancora alcun sostegno finanziario, nonostante abbiano un'occupazione remunerata.<\/strong><\/p>\n\n\n\n<p>Siamo in contatto con Beat Handschin da molto tempo. Attraverso la Fondazione SOS Observer, siamo stati in grado di portare numerosi computer portatili in luoghi dove altrimenti non sarebbe possibile fornire alcun aiuto finanziario. Riceviamo spesso richieste che non possiamo valutare professionalmente a causa di questa situazione iniziale. Abbiamo quindi deciso che in futuro gestiremo tali richieste esclusivamente attraverso la nostra partnership.<\/p>\n\n\n\n<h5 class=\"has-secondary-color has-text-color wp-block-heading\">Come funziona con la Fondazione SOS Observer?<\/h5>\n\n\n\n<p>Di solito indirizziamo le richieste applicabili a un modulo di domanda personalizzato, che pu\u00f2 essere compilato e inviato alla fondazione. Qui vengono fornite informazioni sulla situazione finanziaria e sui motivi per cui \u00e8 necessario un computer portatile.<\/p>\n\n\n\n<p>Dopo la presentazione della domanda, occorrono dalle quattro alle sei settimane prima che la domanda possa essere esaminata. Se la richiesta viene approvata, la consegna del computer portatile da parte nostra richiede solo pochi giorni.<\/p>\n\n\n\n<h5 class=\"has-secondary-color has-text-color wp-block-heading\">Come si \u00e8 arrivati a questo punto?<\/h5>\n\n\n\n<p>Abbiamo chiesto a Beat Hanschin di rispondere ad alcune domande sulla nostra collaborazione finora. Beat Handschin \u00e8 la persona di riferimento per noi della Fondazione SOS Observer.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-background has-secondary-background-color has-secondary-color is-style-dots\"\/>\n\n\n\n<p><strong>Cosa rende <strong>in realt\u00e0<\/strong><\/strong> <strong>la Fondazione SOS Osservatori?<\/strong><\/p>\n\n\n\n<p>La Fondazione SOS Beobachter utilizza le donazioni per sostenere le persone che vivono in Svizzera e che sono colpite dalla povert\u00e0. L'aiuto \u00e8 sussidiario. Ci\u00f2 significa che ogni domanda viene controllata per verificare se il settore pubblico o un fondo di assicurazione sociale, ad esempio, debba pagare qualcosa. Inoltre, il sostegno \u00e8 destinato a uno scopo specifico e mira a risolvere o alleviare un bisogno nel modo pi\u00f9 sostenibile possibile. Ogni anno vengono elaborate circa 2.500 domande.<\/p>\n\n\n\n<p><strong>In quale contesto avete ricevuto finora richieste di laptop?<\/strong><\/p>\n\n\n\n<p>Tali richieste sono quasi sempre legate all'istruzione o alla formazione. Grazie alla formazione o all'aggiornamento, le persone colpite dalla povert\u00e0 possono uscirne a lungo termine. Oggi non \u00e8 praticamente pi\u00f9 possibile senza un computer portatile. Ma anche occuparsi dei propri affari amministrativi o cercare un lavoro \u00e8 praticamente impossibile oggi senza un computer, ancor pi\u00f9 nell'era di Corona.<\/p>\n\n\n\n<p><strong>Perch\u00e9 ora lavora con wLw?<\/strong><\/p>\n\n\n\n<p>Riceviamo molte richieste di computer portatili. Spesso chi cerca aiuto ha idee sbagliate sui requisiti delle apparecchiature necessarie per le applicazioni pi\u00f9 semplici. Per internet, la posta elettronica e cos\u00ec via, di solito sono sufficienti dispositivi semplici. <\/p>\n\n\n\n<p>Poich\u00e9 utilizziamo le donazioni che ci vengono affidate nel modo pi\u00f9 parsimonioso e sensato possibile, nella maggior parte dei casi abbiamo finanziato attrezzature poco costose e costruite ad hoc. Grazie a wLw, possiamo utilizzare le nostre donazioni in modo ancora pi\u00f9 mirato e contare su un partner affidabile.<\/p>\n\n\n\n<p><strong>Come si \u00e8 svolta finora la cooperazione?<\/strong><\/p>\n\n\n\n<p>La collaborazione \u00e8 molto buona e senza complicazioni. Riceviamo molti feedback positivi da coloro che cercano aiuto e per i quali abbiamo organizzato un dispositivo di seconda mano attraverso wLw.<\/p>\n\n\n\n<p><strong>Cosa spera dalla cooperazione in futuro?<\/strong><\/p>\n\n\n\n<p>\u00c8 stimolante lavorare con un'organizzazione di recente creazione che ha un'idea sostenibile per aiutare le persone colpite dalla povert\u00e0. Ci auguriamo di trarre reciproco vantaggio in futuro.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-background has-secondary-background-color has-secondary-color is-style-dots\"\/>\n\n\n\n<p>Siamo anche molto impazienti di vedere le belle storie che ci sar\u00e0 permesso di creare insieme alla fondazione. Dal nostro punto di vista, la partnership finora \u00e8 un passo importante per aiutare il pi\u00f9 rapidamente possibile dove altrimenti non si pu\u00f2 dare aiuto. Grazie per averne fatto parte! \ud83d\ude42<\/p>\n\n\n\n<p><em><strong>- Tobias Sch\u00e4r <\/strong>(Fondatore e Presidente \"Wir lernen weiter\")<\/em>)<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-background has-secondary-background-color has-secondary-color\"\/>\n\n\n\n<h2 class=\"has-secondary-color has-text-color wp-block-heading\">Ulteriori link<\/h2>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-secondary-background-color has-background\" href=\"https:\/\/www.beobachter.ch\/sos-beobachter\" style=\"border-radius:7px\">Fondazione SOS Osservatore<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-secondary-background-color has-background\" href=\"https:\/\/wir-lernen-weiter.ch\/it\/zusatzinformationen-hilfeanfrage\/\" style=\"border-radius:7px\">processi di candidatura wlw<\/a><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Con la seconda edizione del nostro blog sulle partnership, vi presentiamo la Fondazione SOS Observer. Per noi \u00e8 il centro di verifica per tutte le persone che sono colpite dalla povert\u00e0 ma che non ricevono ancora alcun sostegno finanziario, nonostante abbiano un'occupazione remunerata. Siamo in contatto con Beat Handschin da molto tempo. Attraverso la Fondazione SOS Observer siamo riusciti a...<\/p>","protected":false},"author":6,"featured_media":1329,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":2,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tw-meta-no-icon"],"_links":{"self":[{"href":"https:\/\/wir-lernen-weiter.ch\/it\/wp-json\/wp\/v2\/posts\/1327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wir-lernen-weiter.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wir-lernen-weiter.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wir-lernen-weiter.ch\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/wir-lernen-weiter.ch\/it\/wp-json\/wp\/v2\/comments?post=1327"}],"version-history":[{"count":0,"href":"https:\/\/wir-lernen-weiter.ch\/it\/wp-json\/wp\/v2\/posts\/1327\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wir-lernen-weiter.ch\/it\/wp-json\/wp\/v2\/media\/1329"}],"wp:attachment":[{"href":"https:\/\/wir-lernen-weiter.ch\/it\/wp-json\/wp\/v2\/media?parent=1327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wir-lernen-weiter.ch\/it\/wp-json\/wp\/v2\/categories?post=1327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wir-lernen-weiter.ch\/it\/wp-json\/wp\/v2\/tags?post=1327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}