{"id":5930,"date":"2026-04-10T13:54:25","date_gmt":"2026-04-10T12:54:25","guid":{"rendered":"https:\/\/wir-lernen-weiter.ch\/?post_type=ht_kb&#038;p=5930"},"modified":"2026-04-11T08:06:46","modified_gmt":"2026-04-11T07:06:46","slug":"tipps-und-tricks-videodatenbank","status":"publish","type":"ht_kb","link":"https:\/\/wir-lernen-weiter.ch\/it\/knowledge-base\/tipps-und-tricks-videodatenbank\/","title":{"rendered":"Suggerimenti e trucchi: database video"},"content":{"rendered":"<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-info\">Qui troverete un database di video con video e istruzioni che possono aiutarvi nell'uso quotidiano o nell'assistenza. I video sono disponibili in tedesco e in inglese.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-essential-blocks-accordion  root-eb-accordion-35z7u\"><div class=\"eb-parent-wrapper eb-parent-eb-accordion-35z7u\"><div class=\"eb-accordion-container eb-accordion-35z7u\" data-accordion-type=\"accordion\" data-tab-icon=\"dashicons-plus-alt2\" data-expanded-icon=\"dashicons-minus\" data-transition-duration=\"500\"><div class=\"eb-accordion-inner\">\n<div class=\"wp-block-essential-blocks-accordion-item eb-accordion-item-7e36t eb-accordion-wrapper\" data-clickable=\"false\"><div class=\"eb-accordion-title-wrapper eb-accordion-title-wrapper-eb-accordion-35z7u\" tabindex=\"0\"><span class=\"eb-accordion-icon-wrapper eb-accordion-icon-wrapper-eb-accordion-35z7u\"><span class=\"dashicon dashicons dashicons-plus-alt2 eb-accordion-icon\"><\/span><\/span><div class=\"eb-accordion-title-content-wrap title-content-eb-accordion-35z7u\"><h3 class=\"eb-accordion-title\">Zorin OS: primo lancio<\/h3><\/div><\/div><div class=\"eb-accordion-content-wrapper eb-accordion-content-wrapper-eb-accordion-35z7u\"><div class=\"eb-accordion-content\">\n<p class=\"wp-block-paragraph\">Qui potete scoprire come configurare il vostro computer portatile per la prima volta. In questo modo si potr\u00e0 scegliere il giusto layout della tastiera e fare in modo che tutto funzioni senza problemi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Zorin OS: primo lancio (EN)<\/h5>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-9-16 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Suggerimenti e trucchi: avvio iniziale (Zorin OS)\" width=\"563\" height=\"1000\" src=\"https:\/\/www.youtube.com\/embed\/6r2syZZuay0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\">Zorin OS: primo lancio (ENG)<\/h5>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-9-16 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Suggerimenti e trucchi: Cosa fare al primo avvio (Zorin OS)\" width=\"563\" height=\"1000\" src=\"https:\/\/www.youtube.com\/embed\/8ug9wRxQX44?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-accordion-item eb-accordion-item-jbbes eb-accordion-wrapper\" data-clickable=\"false\"><div class=\"eb-accordion-title-wrapper eb-accordion-title-wrapper-eb-accordion-35z7u\" tabindex=\"0\"><span class=\"eb-accordion-icon-wrapper eb-accordion-icon-wrapper-eb-accordion-35z7u\"><span class=\"dashicon dashicons dashicons-plus-alt2 eb-accordion-icon\"><\/span><\/span><div class=\"eb-accordion-title-content-wrap title-content-eb-accordion-35z7u\"><h3 class=\"eb-accordion-title\">Come eseguire uno spegnimento forzato<\/h3><\/div><\/div><div class=\"eb-accordion-content-wrapper eb-accordion-content-wrapper-eb-accordion-35z7u\"><div class=\"eb-accordion-content\">\n<p class=\"wp-block-paragraph\">Qui \u00e8 possibile scoprire come eseguire un arresto forzato:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tenere premuto il pulsante di accensione per 30 secondi<\/li>\n\n\n\n<li>Togliere la mano e attendere 5 secondi<\/li>\n\n\n\n<li>Premere una volta il pulsante di accensione per riavviare il portatile.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon\">Questo \u00e8 utile se il portatile \u00e8 bloccato in modalit\u00e0 di sospensione.<br>Il video \u00e8 riportato di seguito:<br><\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Come si esegue uno spegnimento forzato (DE)<\/h5>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-9-16 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Suggerimenti e trucchi: Come si esegue uno spegnimento forzato?\" width=\"563\" height=\"1000\" src=\"https:\/\/www.youtube.com\/embed\/5V8bLmVQtLI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\">Come eseguire uno spegnimento duro (ENG)<\/h5>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-9-16 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Suggerimenti e trucchi: Come eseguire uno spegnimento forzato\" width=\"563\" height=\"1000\" src=\"https:\/\/www.youtube.com\/embed\/X3C98ZkqMhs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-info\">Se avete domande o se qualcosa non \u00e8 chiaro, contattateci tramite il supporto WhatsApp.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"iawp_total_views":29,"footnotes":""},"ht-kb-category":[58],"ht-kb-tag":[],"class_list":["post-5930","ht_kb","type-ht_kb","status-publish","format-standard","hentry","ht_kb_category-zu-den-laptops"],"_links":{"self":[{"href":"https:\/\/wir-lernen-weiter.ch\/it\/wp-json\/wp\/v2\/ht-kb\/5930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wir-lernen-weiter.ch\/it\/wp-json\/wp\/v2\/ht-kb"}],"about":[{"href":"https:\/\/wir-lernen-weiter.ch\/it\/wp-json\/wp\/v2\/types\/ht_kb"}],"author":[{"embeddable":true,"href":"https:\/\/wir-lernen-weiter.ch\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/wir-lernen-weiter.ch\/it\/wp-json\/wp\/v2\/comments?post=5930"}],"version-history":[{"count":0,"href":"https:\/\/wir-lernen-weiter.ch\/it\/wp-json\/wp\/v2\/ht-kb\/5930\/revisions"}],"wp:attachment":[{"href":"https:\/\/wir-lernen-weiter.ch\/it\/wp-json\/wp\/v2\/media?parent=5930"}],"wp:term":[{"taxonomy":"ht_kb_category","embeddable":true,"href":"https:\/\/wir-lernen-weiter.ch\/it\/wp-json\/wp\/v2\/ht-kb-category?post=5930"},{"taxonomy":"ht_kb_tag","embeddable":true,"href":"https:\/\/wir-lernen-weiter.ch\/it\/wp-json\/wp\/v2\/ht-kb-tag?post=5930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}