{"id":1327,"date":"2021-02-06T10:32:49","date_gmt":"2021-02-06T10:32:49","guid":{"rendered":"https:\/\/wir-lernen-weiter.ch\/?p=1327"},"modified":"2022-03-30T13:43:15","modified_gmt":"2022-03-30T12:43:15","slug":"anderen-helfen-2-4-working-poor","status":"publish","type":"post","link":"https:\/\/wir-lernen-weiter.ch\/fr\/anderen-helfen-2-4-working-poor\/","title":{"rendered":"Aider les autres (2\/4) : Travailleurs pauvres"},"content":{"rendered":"<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/wir-lernen-weiter.ch\/wp-content\/uploads\/2021\/02\/2021-02-06-11_11_06-Praesentation1-PowerPoint-1024x682.png\" alt=\"\" class=\"wp-image-1329\" srcset=\"https:\/\/wir-lernen-weiter.ch\/wp-content\/uploads\/2021\/02\/2021-02-06-11_11_06-Praesentation1-PowerPoint-1024x682.png 1024w, https:\/\/wir-lernen-weiter.ch\/wp-content\/uploads\/2021\/02\/2021-02-06-11_11_06-Praesentation1-PowerPoint-300x200.png 300w, https:\/\/wir-lernen-weiter.ch\/wp-content\/uploads\/2021\/02\/2021-02-06-11_11_06-Praesentation1-PowerPoint-768x511.png 768w, https:\/\/wir-lernen-weiter.ch\/wp-content\/uploads\/2021\/02\/2021-02-06-11_11_06-Praesentation1-PowerPoint.png 1170w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>L'\u00e9quipe SOS Observateurs<\/figcaption><\/figure>\n\n\n\n<p><strong>Dans la deuxi\u00e8me \u00e9dition de notre blog sur nos partenariats, nous vous pr\u00e9sentons la fondation SOS Beobachter. Elle constitue pour nous l'organe de contr\u00f4le pour toutes les personnes touch\u00e9es par la pauvret\u00e9, mais qui ne re\u00e7oivent pourtant pas d'aide financi\u00e8re - malgr\u00e9 leur activit\u00e9 professionnelle.<\/strong><\/p>\n\n\n\n<p>Nous \u00e9tions d\u00e9j\u00e0 en contact avec Beat Handschin depuis longtemps. Par le biais de la fondation SOS Observateurs, nous avons d\u00e9j\u00e0 pu apporter de nombreux ordinateurs portables l\u00e0 o\u00f9 aucune autre aide financi\u00e8re ne peut \u00eatre accord\u00e9e. Nous recevons r\u00e9guli\u00e8rement des demandes que nous ne pouvons pas \u00e9valuer de mani\u00e8re professionnelle en raison de cette situation initiale. Nous avons donc d\u00e9cid\u00e9 qu'\u00e0 l'avenir, nous traiterions ces demandes exclusivement par le biais de notre partenariat.<\/p>\n\n\n\n<h5 class=\"has-secondary-color has-text-color wp-block-heading\">Comment cela fonctionne-t-il avec la fondation SOS Beobachter ?<\/h5>\n\n\n\n<p>En r\u00e8gle g\u00e9n\u00e9rale, nous dirigeons les demandes pertinentes directement vers un formulaire de demande adapt\u00e9, qui peut ensuite \u00eatre rempli et envoy\u00e9 \u00e0 la fondation. Les informations relatives \u00e0 la situation financi\u00e8re ainsi que les raisons pour lesquelles un ordinateur portable est n\u00e9cessaire y sont indiqu\u00e9es.<\/p>\n\n\n\n<p>Une fois la demande d\u00e9pos\u00e9e, il faut compter entre quatre et six semaines pour qu'elle soit examin\u00e9e. Si la demande est accept\u00e9e, il ne reste plus que quelques jours avant que l'ordinateur portable ne soit livr\u00e9 par notre interm\u00e9diaire.<\/p>\n\n\n\n<h5 class=\"has-secondary-color has-text-color wp-block-heading\">Comment \u00e7a s'est pass\u00e9 jusqu'\u00e0 pr\u00e9sent ?<\/h5>\n\n\n\n<p>Nous avons demand\u00e9 \u00e0 Beat Hanschin de r\u00e9pondre \u00e0 quelques questions sur notre collaboration jusqu'\u00e0 pr\u00e9sent. Beat Handschin est notre principal interlocuteur \u00e0 la fondation SOS Beobachter.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-background has-secondary-background-color has-secondary-color is-style-dots\"\/>\n\n\n\n<p><strong>Que fait <strong>en fait<\/strong><\/strong> <strong>la fondation SOS Beobachter ?<\/strong><\/p>\n\n\n\n<p>La fondation SOS Observateurs soutient, gr\u00e2ce \u00e0 des dons, des personnes vivant en Suisse et touch\u00e9es par la pauvret\u00e9. L'aide est apport\u00e9e de mani\u00e8re subsidiaire. Cela signifie que pour chaque demande, on v\u00e9rifie si les pouvoirs publics ou une assurance sociale ne doivent pas prendre en charge quelque chose, par exemple. En outre, l'aide est affect\u00e9e \u00e0 un but pr\u00e9cis et doit, dans la mesure du possible, r\u00e9soudre ou att\u00e9nuer durablement une d\u00e9tresse. Chaque ann\u00e9e, environ 2 500 demandes sont trait\u00e9es.<\/p>\n\n\n\n<p><strong>Dans quel contexte avez-vous re\u00e7u des demandes d'ordinateurs portables jusqu'\u00e0 pr\u00e9sent ?<\/strong><\/p>\n\n\n\n<p>Ces demandes sont presque toujours li\u00e9es \u00e0 une formation ou \u00e0 un perfectionnement. Gr\u00e2ce \u00e0 une formation ou \u00e0 un perfectionnement, il peut \u00eatre possible pour les personnes en situation de pauvret\u00e9 de sortir durablement de la pauvret\u00e9. Aujourd'hui, cela n'est pratiquement plus possible sans ordinateur portable. Mais s'occuper de ses propres affaires administratives ou chercher un emploi est aujourd'hui pratiquement impossible sans ordinateur - \u00e0 plus forte raison \u00e0 l'\u00e9poque de Corona.<\/p>\n\n\n\n<p><strong>Pourquoi travaillez-vous maintenant avec wLw ?<\/strong><\/p>\n\n\n\n<p>Nous recevons de tr\u00e8s nombreuses demandes d'ordinateurs portables. Souvent, les personnes qui cherchent de l'aide se font une id\u00e9e erron\u00e9e des exigences en mati\u00e8re d'appareils, qui sont n\u00e9cessaires pour des applications simples. Pour Internet, le courrier \u00e9lectronique, etc., des appareils simples suffisent g\u00e9n\u00e9ralement. <\/p>\n\n\n\n<p>Comme nous utilisons les dons qui nous sont confi\u00e9s de la mani\u00e8re la plus \u00e9conome et la plus judicieuse possible, nous avons financ\u00e9 dans la plupart des cas des appareils avantageux et ad\u00e9quats. Gr\u00e2ce \u00e0 wLw, nous pouvons utiliser nos dons de mani\u00e8re encore plus cibl\u00e9e et nous appuyer sur un partenaire fiable.<\/p>\n\n\n\n<p><strong>Comment s'est d\u00e9roul\u00e9e la coop\u00e9ration jusqu'\u00e0 pr\u00e9sent ?<\/strong><\/p>\n\n\n\n<p>La collaboration se d\u00e9roule tr\u00e8s bien et sans complications. Nous recevons de tr\u00e8s nombreux retours positifs de la part des personnes en qu\u00eate d'aide \u00e0 qui nous avons procur\u00e9 un appareil d'occasion via wLw.<\/p>\n\n\n\n<p><strong>Qu'attendez-vous de cette collaboration pour l'avenir ?<\/strong><\/p>\n\n\n\n<p>C'est inspirant de travailler avec une organisation nouvellement cr\u00e9\u00e9e qui s'engage avec une id\u00e9e durable pour les personnes touch\u00e9es par la pauvret\u00e9. Nous nous r\u00e9jouissons de pouvoir continuer \u00e0 profiter mutuellement de nos efforts \u00e0 l'avenir.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-background has-secondary-background-color has-secondary-color is-style-dots\"\/>\n\n\n\n<p>Nous aussi, nous nous r\u00e9jouissons beaucoup des belles histoires que nous pourrons cr\u00e9er avec la fondation. Le partenariat conclu jusqu'\u00e0 pr\u00e9sent est \u00e0 nos yeux une \u00e9tape importante pour aider le plus rapidement possible l\u00e0 o\u00f9 il n'est pas possible d'aider autrement. Merci de nous rejoindre ! \ud83d\ude42<\/p>\n\n\n\n<p><em><strong>- Tobias Sch\u00e4r <\/strong>(Fondateur et pr\u00e9sident \"Wir lernen weiter\")<\/em>)<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-background has-secondary-background-color has-secondary-color\"\/>\n\n\n\n<h2 class=\"has-secondary-color has-text-color wp-block-heading\">Liens compl\u00e9mentaires<\/h2>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-secondary-background-color has-background\" href=\"https:\/\/www.beobachter.ch\/sos-beobachter\" style=\"border-radius:7px\">Fondation SOS Beobachter<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-secondary-background-color has-background\" href=\"https:\/\/wir-lernen-weiter.ch\/fr\/zusatzinformationen-hilfeanfrage\/\" style=\"border-radius:7px\">processus de demande wlw<\/a><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Dans la deuxi\u00e8me \u00e9dition de notre blog sur nos partenariats, nous vous pr\u00e9sentons la fondation SOS Beobachter. Elle constitue pour nous l'organe de contr\u00f4le pour toutes les personnes touch\u00e9es par la pauvret\u00e9, mais qui ne re\u00e7oivent pas d'aide financi\u00e8re - malgr\u00e9 leur activit\u00e9 professionnelle. Nous \u00e9tions d\u00e9j\u00e0 en contact avec Beat Handschin depuis longtemps. Par l'interm\u00e9diaire de la fondation SOS-Beobachter, nous avons pu...<\/p>","protected":false},"author":6,"featured_media":1329,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":2,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tw-meta-no-icon"],"_links":{"self":[{"href":"https:\/\/wir-lernen-weiter.ch\/fr\/wp-json\/wp\/v2\/posts\/1327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wir-lernen-weiter.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wir-lernen-weiter.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wir-lernen-weiter.ch\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/wir-lernen-weiter.ch\/fr\/wp-json\/wp\/v2\/comments?post=1327"}],"version-history":[{"count":0,"href":"https:\/\/wir-lernen-weiter.ch\/fr\/wp-json\/wp\/v2\/posts\/1327\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wir-lernen-weiter.ch\/fr\/wp-json\/wp\/v2\/media\/1329"}],"wp:attachment":[{"href":"https:\/\/wir-lernen-weiter.ch\/fr\/wp-json\/wp\/v2\/media?parent=1327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wir-lernen-weiter.ch\/fr\/wp-json\/wp\/v2\/categories?post=1327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wir-lernen-weiter.ch\/fr\/wp-json\/wp\/v2\/tags?post=1327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}